{"id":974,"date":"2017-11-13T20:41:37","date_gmt":"2017-11-13T20:41:37","guid":{"rendered":"https:\/\/www.caminhosdeferro.pt\/loja\/?post_type=product&#038;p=974"},"modified":"2021-11-10T20:58:11","modified_gmt":"2021-11-10T20:58:11","slug":"trainspotter-vi-dezembro-2017-pre-venda-ate-09-de-dezembro","status":"publish","type":"product","link":"https:\/\/www.caminhosdeferro.pt\/loja\/produto\/trainspotter-vi-dezembro-2017-pre-venda-ate-09-de-dezembro\/","title":{"rendered":"Trainspotter VI &#8211; As locomotivas 5600 e Renfe 252"},"content":{"rendered":"<p><strong>Sexta edi\u00e7\u00e3o impressa da Trainspotter<\/strong><\/p>\n<p>A presente edi\u00e7\u00e3o inclui:<\/p>\n<ul>\n<li>Aquisi\u00e7\u00e3o e ensaios das 5600 da CP<\/li>\n<li>Caracter\u00edsticas T\u00e9cnicas das 5600 da CP<\/li>\n<li>As locomotivas 5600 no servi\u00e7o de passageiros<\/li>\n<li>As locomotivas 5600 no servi\u00e7o de mercadorias<\/li>\n<li>Aquisi\u00e7\u00e3o das locomotivas 252 da Renfe<\/li>\n<li>As locomotivas 252 de bitola europeia<\/li>\n<li>As locomotivas 252 de bitola ib\u00e9rica<\/li>\n<li>O futuro das 252 e 5600<\/li>\n<li>Os modelos \u00e0 escala das 252 e 5600.<\/li>\n<\/ul>\n<p>Revista 100% a cores e com papel de muito boa qualidade. M\u00ednimo de 68 p\u00e1ginas, encaderna\u00e7\u00e3o com capa fresada e colada e lombada identificadora.<\/p>\n<p>Ver em informa\u00e7\u00e3o adicional detalhes sobre as possibilidades de entrega.<\/p>\n<p>A revista Trainspotter \u00e9 editada pelo portal <a href=\"http:\/\/www.portugalferroviario.net\" target=\"_blank\" rel=\"noopener noreferrer\">Portugal Ferrovi\u00e1rio<\/a> e a sua edi\u00e7\u00e3o impressa \u00e9 cedida gratuitamente \u00e0 APAC, que a imprime e distribui. As verbas reunidas permitir\u00e3o investir em projetos de preserva\u00e7\u00e3o ferrovi\u00e1ria. Comprar a Trainspotter \u00e9 colaborar com a preserva\u00e7\u00e3o da mem\u00f3ria coletiva!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Trainspotter\u00a0VI \u00e9 dedicada \u00e0s locomotivas 5600 da CP e 252 da Renfe, sendo uma parceria entre Portugal Ferrovi\u00e1rio e Revista TREN, que asseguram edi\u00e7\u00f5es em Portugal e em Espanha.<\/p>\n<p>Nos 25 anos das locomotivas Eurosprinter na pen\u00ednsula Ib\u00e9rica este n\u00famero marca uma etapa fundamental nas s\u00e9ries dos pa\u00edses vizinhos, momento de olhar para a carreira preenchida at\u00e9 aqui e para um futuro que parece apontar em dire\u00e7\u00f5es muito distintas de um lado e de outro da fronteira.<\/p>\n<p>Neste n\u00famero de anivers\u00e1rio contamos ainda com as melhores imagens para fazer desta edi\u00e7\u00e3o n\u00e3o uma edi\u00e7\u00e3o de resumo hist\u00f3rico de uma carreira j\u00e1 terminada mas antes um balan\u00e7o da carreira destas locomotivas, raz\u00e3o pela qual apresentamos uma estrutura\u00e7\u00e3o diferenciada de n\u00fameros monogr\u00e1ficos anteriores.<\/p>\n<p>At\u00e9 dia 09 de Dezembro a revista conta com um pre\u00e7o especial e com garantia de disponibilidade.<\/p>\n","protected":false},"featured_media":976,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[11],"product_tag":[98,99],"class_list":["post-974","product","type-product","status-publish","has-post-thumbnail","product_cat-trainspotter-versao-impressa","product_tag-cp-5600","product_tag-renfe-252","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.caminhosdeferro.pt\/loja\/wp-json\/wp\/v2\/product\/974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caminhosdeferro.pt\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.caminhosdeferro.pt\/loja\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caminhosdeferro.pt\/loja\/wp-json\/wp\/v2\/comments?post=974"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caminhosdeferro.pt\/loja\/wp-json\/wp\/v2\/media\/976"}],"wp:attachment":[{"href":"https:\/\/www.caminhosdeferro.pt\/loja\/wp-json\/wp\/v2\/media?parent=974"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.caminhosdeferro.pt\/loja\/wp-json\/wp\/v2\/product_brand?post=974"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.caminhosdeferro.pt\/loja\/wp-json\/wp\/v2\/product_cat?post=974"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.caminhosdeferro.pt\/loja\/wp-json\/wp\/v2\/product_tag?post=974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}